{"id":326,"count":2,"description":"","link":"https:\/\/www.collephoto.com\/en\/tag\/pieve-valdicastello\/","name":"Pieve Valdicastello","slug":"pieve-valdicastello","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pieve Valdicastello Archivi | COLLE Photography<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pieve Valdicastello Archivi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.collephoto.com\/en\/tag\/pieve-valdicastello\/\" \/>\n<meta property=\"og:site_name\" content=\"COLLE Photography\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Alessan03264914\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/tag\\\/pieve-valdicastello\\\/\",\"url\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/tag\\\/pieve-valdicastello\\\/\",\"name\":\"Pieve Valdicastello Archivi | COLLE Photography\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/tag\\\/pieve-valdicastello\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/tag\\\/pieve-valdicastello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pieve Valdicastello\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/\",\"name\":\"COLLE Photography\",\"description\":\"Alessandro Colle | Fotografo matrimonio Toscana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/#organization\",\"name\":\"Collephoto Studio\",\"url\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.collephoto.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/collephoto-contacts.png\",\"contentUrl\":\"https:\\\/\\\/www.collephoto.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/collephoto-contacts.png\",\"width\":1541,\"height\":378,\"caption\":\"Collephoto Studio\"},\"image\":{\"@id\":\"https:\\\/\\\/www.collephoto.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BestTuscanyWeddingPhotographer\\\/\",\"https:\\\/\\\/x.com\\\/Alessan03264914\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pieve Valdicastello Archivi | COLLE Photography","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Pieve Valdicastello Archivi","og_url":"https:\/\/www.collephoto.com\/en\/tag\/pieve-valdicastello\/","og_site_name":"COLLE Photography","twitter_card":"summary_large_image","twitter_site":"@Alessan03264914","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.collephoto.com\/en\/tag\/pieve-valdicastello\/","url":"https:\/\/www.collephoto.com\/en\/tag\/pieve-valdicastello\/","name":"Pieve Valdicastello Archivi | COLLE Photography","isPartOf":{"@id":"https:\/\/www.collephoto.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.collephoto.com\/en\/tag\/pieve-valdicastello\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.collephoto.com\/en\/tag\/pieve-valdicastello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.collephoto.com\/en\/"},{"@type":"ListItem","position":2,"name":"Pieve Valdicastello"}]},{"@type":"WebSite","@id":"https:\/\/www.collephoto.com\/en\/#website","url":"https:\/\/www.collephoto.com\/en\/","name":"COLLE Photography","description":"Alessandro Colle | Fotografo matrimonio Toscana","publisher":{"@id":"https:\/\/www.collephoto.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.collephoto.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.collephoto.com\/en\/#organization","name":"Collephoto Studio","url":"https:\/\/www.collephoto.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.collephoto.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.collephoto.com\/wp-content\/uploads\/2018\/12\/collephoto-contacts.png","contentUrl":"https:\/\/www.collephoto.com\/wp-content\/uploads\/2018\/12\/collephoto-contacts.png","width":1541,"height":378,"caption":"Collephoto Studio"},"image":{"@id":"https:\/\/www.collephoto.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BestTuscanyWeddingPhotographer\/","https:\/\/x.com\/Alessan03264914"]}]}},"_links":{"self":[{"href":"https:\/\/www.collephoto.com\/en\/wp-json\/wp\/v2\/tags\/326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collephoto.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.collephoto.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.collephoto.com\/en\/wp-json\/wp\/v2\/posts?tags=326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}